{"id":8206,"date":"2022-07-06T11:13:19","date_gmt":"2022-07-06T15:13:19","guid":{"rendered":"http:\/\/explorelesmines.com\/?post_type=contenu&#038;p=8206"},"modified":"2026-04-23T09:35:45","modified_gmt":"2026-04-23T13:35:45","slug":"diagnostic-sectoriel","status":"publish","type":"contenu","link":"https:\/\/explorelesmines.com\/fr\/diagnostic-sectoriel\/","title":{"rendered":"Diagnostic sectoriel"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8206\" class=\"elementor elementor-8206\" data-elementor-post-type=\"contenu\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-7311bea elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"7311bea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a8aa80 ae-bg-gallery-type-default\" data-id=\"3a8aa80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6118f6 elementor-widget elementor-widget-heading\" data-id=\"e6118f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Diagnostic sectoriel<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d18aea4 elementor-widget elementor-widget-text-editor\" data-id=\"d18aea4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Les objectifs principaux du Diagnostic sectoriel sont de documenter l\u2019\u00e9tat actuel du secteur minier ainsi que mettre en lumi\u00e8re les tendances et les d\u00e9fis de l\u2019industrie sur le plan des pratiques de gestion des ressources humaines et du d\u00e9veloppement des comp\u00e9tences de la main\u2011d\u2019\u0153uvre.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-d1c2516 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"d1c2516\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9ecb13b ae-bg-gallery-type-default\" data-id=\"9ecb13b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d573b1 hover-item-img elementor-widget elementor-widget-image\" data-id=\"1d573b1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/explorelesmines.com\/wp-content\/uploads\/2026\/04\/VF-pour-Web-Diagnostic-sectoriel-mines-20260327-1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/explorelesmines.com\/wp-content\/uploads\/2026\/04\/VF-pour-Web-Diagnostic-sectoriel-mines-20260327-P1.jpg\" class=\"attachment-full size-full wp-image-34260\" alt=\"\" srcset=\"https:\/\/explorelesmines.com\/wp-content\/uploads\/2026\/04\/VF-pour-Web-Diagnostic-sectoriel-mines-20260327-P1.jpg 791w, https:\/\/explorelesmines.com\/wp-content\/uploads\/2026\/04\/VF-pour-Web-Diagnostic-sectoriel-mines-20260327-P1-232x300.jpg 232w, https:\/\/explorelesmines.com\/wp-content\/uploads\/2026\/04\/VF-pour-Web-Diagnostic-sectoriel-mines-20260327-P1-768x994.jpg 768w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d310f5d elementor-align-justify hover-item-btn elementor-widget elementor-widget-button\" data-id=\"d310f5d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/explorelesmines.com\/wp-content\/uploads\/2026\/04\/VF-pour-Web-Diagnostic-sectoriel-mines-20260327-1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulter le document<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dd1e1de ae-bg-gallery-type-default\" data-id=\"dd1e1de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-668beba hover-item-img elementor-widget elementor-widget-image\" data-id=\"668beba\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/wp-content\/uploads\/2022\/07\/Diagnostic_sectoriel_VF_INTERACTIVE_PDF_revise.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"517\" src=\"https:\/\/explorelesmines.com\/wp-content\/uploads\/2022\/07\/diagnostic_sectoriel_VF_INTERACTIVE_pdf_revise.jpg\" class=\"attachment-full size-full wp-image-10981\" alt=\"\" srcset=\"https:\/\/explorelesmines.com\/wp-content\/uploads\/2022\/07\/diagnostic_sectoriel_VF_INTERACTIVE_pdf_revise.jpg 400w, https:\/\/explorelesmines.com\/wp-content\/uploads\/2022\/07\/diagnostic_sectoriel_VF_INTERACTIVE_pdf_revise-232x300.jpg 232w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a672d elementor-align-justify hover-item-btn elementor-widget elementor-widget-button\" data-id=\"13a672d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/wp-content\/uploads\/2022\/07\/Diagnostic_sectoriel_VF_INTERACTIVE_PDF_revise.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulter le document<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4be4c3a ae-bg-gallery-type-default\" data-id=\"4be4c3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Diagnostic sectoriel Les objectifs principaux du Diagnostic sectoriel sont de documenter l\u2019\u00e9tat actuel du secteur minier ainsi que mettre en lumi\u00e8re les tendances et les d\u00e9fis de l\u2019industrie sur le plan des pratiques de gestion des ressources humaines et du d\u00e9veloppement des comp\u00e9tences de la main\u2011d\u2019\u0153uvre. Consulter le document Consulter le document<\/p>\n","protected":false},"featured_media":21161,"parent":0,"menu_order":0,"template":"","meta":{"_seopress_robots_primary_cat":""},"acf":[],"_links":{"self":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/contenu\/8206"}],"collection":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/contenu"}],"about":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/types\/contenu"}],"version-history":[{"count":24,"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/contenu\/8206\/revisions"}],"predecessor-version":[{"id":34360,"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/contenu\/8206\/revisions\/34360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/media\/21161"}],"wp:attachment":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/media?parent=8206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}