{"id":16810,"date":"2022-10-29T04:56:44","date_gmt":"2022-10-29T08:56:44","guid":{"rendered":"http:\/\/explorelesmines.com\/?post_type=calendrier&#038;p=16810"},"modified":"2025-11-04T08:11:19","modified_gmt":"2025-11-04T13:11:19","slug":"formation-specialisee-en-electricite-pour-equipement-mobile","status":"publish","type":"calendrier","link":"https:\/\/explorelesmines.com\/fr\/calendrier\/formation-specialisee-en-electricite-pour-equipement-mobile\/","title":{"rendered":"Formation sp\u00e9cialis\u00e9e en \u00e9lectricit\u00e9 pour \u00e9quipement mobile"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16810\" class=\"elementor elementor-16810\" data-elementor-post-type=\"calendrier\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-22529f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"22529f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5d1915 ae-bg-gallery-type-default\" data-id=\"b5d1915\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-81a14c2 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"81a14c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9f6ebb ae-bg-gallery-type-default\" data-id=\"e9f6ebb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a7a4a4 elementor-widget elementor-widget-text-editor\" data-id=\"4a7a4a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Formation ax\u00e9e sur l\u2019acquisition des connaissances fondamentales en \u00e9lectricit\u00e9 applicables tous les types d\u2019\u00e9quipement mobile dans un contexte minier, en mettant l\u2019accent sur la s\u00e9curit\u00e9 de l\u2019environnement de travail.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec01069 ae-bg-gallery-type-default\" data-id=\"ec01069\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2395e70 elementor-widget elementor-widget-video\" data-id=\"2395e70\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=dmh9jVgZ-n8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-694ce14 elementor-widget elementor-widget-heading\" data-id=\"694ce14\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Client\u00e8le cible<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35476cf elementor-widget elementor-widget-text-editor\" data-id=\"35476cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>M\u00e9caniciens d&rsquo;\u00e9quipements mobiles et techniciens en entretien m\u00e9canique.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6555487 elementor-widget elementor-widget-heading\" data-id=\"6555487\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Objectifs<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-200b26e single-event-points elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"200b26e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/explorelesmines.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">D\u00e9velopper des connaissances fondamentales en \u00e9lectricit\u00e9 pour les \u00e9quipements mobiles, notamment par la lecture de plans, l\u2019\u00e9tablissement de diagnostics de base, le d\u00e9pannage et le survoltage;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accro\u00eetre la ma\u00eetrise de notions li\u00e9s \u00e0 l\u2019\u00e9lectricit\u00e9 dans un environnement sain et s\u00e9curitaire.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e4a243 elementor-widget elementor-widget-heading\" data-id=\"5e4a243\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Th\u00e8mes abord\u00e9s<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d046835 single-event-points elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d046835\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Principes de base en \u00e9lectricit\u00e9;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Utilisation d'appareils de diagnostic;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lecture de plans et diagnostics de base;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Circuit de charge;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Circuit de d\u00e9marrage;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9lectronique de base;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Survoltage d'\u00e9quipement minier mobile.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c066309 elementor-widget elementor-widget-heading\" data-id=\"c066309\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pour vous inscrire ou pour obtenir de plus amples renseignements, communiquez avec :<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb0373 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"9fb0373\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-nurse\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M319.41,320,224,415.39,128.59,320C57.1,323.1,0,381.6,0,453.79A58.21,58.21,0,0,0,58.21,512H389.79A58.21,58.21,0,0,0,448,453.79C448,381.6,390.9,323.1,319.41,320ZM224,304A128,128,0,0,0,352,176V65.82a32,32,0,0,0-20.76-30L246.47,4.07a64,64,0,0,0-44.94,0L116.76,35.86A32,32,0,0,0,96,65.82V176A128,128,0,0,0,224,304ZM184,71.67a5,5,0,0,1,5-5h21.67V45a5,5,0,0,1,5-5h16.66a5,5,0,0,1,5,5V66.67H259a5,5,0,0,1,5,5V88.33a5,5,0,0,1-5,5H237.33V115a5,5,0,0,1-5,5H215.67a5,5,0,0,1-5-5V93.33H189a5,5,0,0,1-5-5ZM144,160H304v16a80,80,0,0,1-160,0Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Service du d\u00e9veloppement des comp\u00e9tences<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:4186539254\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">418-653-9254, poste 222<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:formations@csmomines.qc.ca\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">formations@csmomines.qc.ca<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-264892d elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"264892d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d0202a ae-bg-gallery-type-default\" data-id=\"6d0202a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b1ad78 elementor-widget elementor-widget-heading\" data-id=\"8b1ad78\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Modalit\u00e9s d\u2019inscription<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-886200d single-event-points elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"886200d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L\u2019inscription des employ\u00e9s doit \u00eatre faite par l\u2019entremise d\u2019un responsable des ressources humaines ou d\u2019un superviseur de l\u2019entreprise.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frais d'inscription entre 300 $ et 600 $ par participant selon l'endroit et la dur\u00e9e de la formation.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"14\" viewBox=\"0 0 27 14\" fill=\"none\"><path d=\"M15.0605 0.561219C15.3599 0.276233 15.7582 0.118681 16.1715 0.121809C16.5848 0.124936 16.9807 0.288498 17.2757 0.577981C17.5707 0.867464 17.7417 1.26023 17.7527 1.67339C17.7636 2.08655 17.6136 2.4878 17.3343 2.79247L8.85555 13.3962C8.70975 13.5533 8.53379 13.6793 8.33818 13.7667C8.14257 13.8542 7.93132 13.9014 7.71708 13.9053C7.50284 13.9093 7.29 13.87 7.09128 13.7898C6.89256 13.7097 6.71206 13.5902 6.56055 13.4387L0.937797 7.81597C0.781212 7.67006 0.65562 7.49411 0.568512 7.29861C0.481404 7.10312 0.434566 6.89207 0.43079 6.67808C0.427014 6.46409 0.466379 6.25152 0.546536 6.05307C0.626694 5.85463 0.746001 5.67435 0.897341 5.52301C1.04868 5.37167 1.22895 5.25237 1.4274 5.17221C1.62585 5.09205 1.83841 5.05269 2.05241 5.05646C2.2664 5.06024 2.47744 5.10708 2.67294 5.19418C2.86844 5.28129 3.04439 5.40689 3.1903 5.56347L7.64005 10.0111L15.018 0.60797C15.0313 0.591564 15.0455 0.575952 15.0605 0.561219ZM13.1055 11.4837L15.0605 13.4387C15.212 13.5899 15.3924 13.7091 15.5909 13.789C15.7894 13.869 16.002 13.9082 16.216 13.9042C16.43 13.9003 16.641 13.8532 16.8364 13.7659C17.0318 13.6787 17.2077 13.5529 17.3534 13.3962L25.8364 2.79247C25.9888 2.64202 26.1093 2.46241 26.1907 2.26435C26.2722 2.0663 26.3128 1.85387 26.3104 1.63974C26.3079 1.42562 26.2622 1.21419 26.1762 1.01809C26.0902 0.821989 25.9655 0.645235 25.8097 0.498382C25.6538 0.351529 25.47 0.237589 25.2691 0.163368C25.0682 0.0891472 24.8545 0.0561658 24.6406 0.0663945C24.4267 0.0766232 24.217 0.129853 24.0242 0.222903C23.8313 0.315952 23.6592 0.446915 23.518 0.60797L16.1379 10.0111L15.1073 8.97834L13.1034 11.4837H13.1055Z\" fill=\"#AED043\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Des frais de d\u00e9placement et d\u2019h\u00e9bergement peuvent \u00eatre rembours\u00e9s aux travailleurs participants, sous certaines conditions.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":24208,"template":"","meta":{"_seopress_robots_primary_cat":""},"acf":[],"_links":{"self":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/calendrier\/16810"}],"collection":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/calendrier"}],"about":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/types\/calendrier"}],"version-history":[{"count":29,"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/calendrier\/16810\/revisions"}],"predecessor-version":[{"id":32767,"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/calendrier\/16810\/revisions\/32767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/media\/24208"}],"wp:attachment":[{"href":"https:\/\/explorelesmines.com\/fr\/wp-json\/wp\/v2\/media?parent=16810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}